{"id":107,"date":"2017-06-01T18:23:20","date_gmt":"2017-06-01T18:23:20","guid":{"rendered":"http:\/\/www.concisa.net.ve\/2017\/?page_id=107"},"modified":"2017-07-21T19:56:06","modified_gmt":"2017-07-21T19:56:06","slug":"pst-envio","status":"publish","type":"page","link":"https:\/\/concisa.net.ve\/2017\/pst-envio\/","title":{"rendered":"PST 2017 &#8211; Env\u00edo de un PST"},"content":{"rendered":"\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a56d346f23fc\" class=\"master-slider-parent ms-parent-id-17\" style=\"\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a56d346f23fc\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"   >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/concisa.net.ve\/2017\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/concisa.net.ve\/2017\/wp-content\/uploads\/sites\/6\/2017\/05\/bg-concisa15-1500x150.jpg\" \/>\n\n\t\t\t\t\t<div  class=\"ms-layer  msp-cn-2-1\" style=\"\"      data-ease=\"easeOutQuint\"                data-offset-x=\"0\" data-offset-y=\"0\" data-origin=\"mc\"   >\nPST 2017 \u2013 Env\u00edo de un PST<\/div>\n\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_23fc = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_23fc.setup(\"MS6a56d346f23fc\", {\n\t\t\t\twidth           : 1500,\n\t\t\t\theight          : 150,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : false,\n\t\t\t\tswipe           : false,\n\t\t\t\tmouse           : false,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fullwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : false,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : false,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 0,\n\t\t\t\theightLimit     : true,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : true,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 20,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_23fc );\n\t\t});\n\t\t<\/script>\n\n\n<h2>Env\u00edo de un PST<\/h2>\n<p>Los PSTs deben estar escritos en castellano y defendido en el per\u00edodo comprendido del 01\/07\/2016 al 31\/07\/2017 en los programas de las carreras de computaci\u00f3n, inform\u00e1tica y sistemas. Los trabajos enviados pueden ser individuales o grupales. Para enviar un PST, se requiere un \u00fanico archivo PDF con tres partes:<\/p>\n<ol>\n<li>un resumen (versi\u00f3n corta del PST). El resumen debe contener entre 6 y 12 p\u00e1ginas que describan el contexto del trabajo, justificaci\u00f3n e importancia, objetivos y logros alcanzados. El formato es libre, en tama\u00f1o carta (8.5\u2033 x 11\u2033), interlineado sencillo. La primera p\u00e1gina del resumen es para identificar el PST, y debe constar del t\u00edtulo del PST, el nombre y correo electr\u00f3nico del autor (o de los autores), la instituci\u00f3n de afiliaci\u00f3n, el nombre y correo electr\u00f3nico del tutor (o de los tutores), y la fecha de defensa.<\/li>\n<li>un documento probatorio de la defensa del PST donde aparezca la fecha de esta (ej., acta o veredicto de defensa)<\/li>\n<li>el informe final completo del PST.<\/li>\n<\/ol>\n<p>El archivo PDF debe ser sometido a trav\u00e9s de <a href=\"https:\/\/easychair.org\/conferences\/?conf=evi2017\" target=\"_blank\"n>EasyChair<\/a>. Es importante recordar que debe ser un \u00fanico archivo PDF, con las tres partes mencionadas anteriormente, y en el orden especificado (resumen, documento probatorio, e informe final completo del PST).<\/p>\n<p>En caso que a\u00fan no tenga cuenta en EasyChair, la puede crear a trav\u00e9s de este <a href=\"https:\/\/www.easychair.org\/account\/signup.cgi\" target=\"_blank\">enlace<\/a>.<\/p>\n<h2>Llamado al Concurso Nacional de PSTs (Versi\u00f3n PDF)<\/h2>\n<p>El llamado al concurso nacional de PSTs 2017 vence el domingo 13 de agosto de 2017. Pueden descargar la versi\u00f3n PDF del llamado al concurso nacional de PSTs en el siguiente <a href=\"http:\/\/www.concisa.net.ve\/2017\/wp-content\/uploads\/sites\/6\/2017\/07\/PST-Primer-Llamado-v2.0.pdf\" target=\"_blank\">enlace<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> PST 2017 \u2013 Env\u00edo de un PST ( window.MSReady = window.MSReady || [] ).push( function( $ ) { &#8220;use strict&#8221;; var masterslider_5443 = new MasterSlider(); \/\/ slider controls \/\/ slider setup masterslider_5443.setup(&#8220;MS6a56d34715443&#8221;, { width : 1500, height : 150, minHeight : 0, space : 0, start : 1, grabCursor : false, swipe : false, [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-107","page","type-page","status-publish","hentry","odd"],"_links":{"self":[{"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/pages\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":0,"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/pages\/107\/revisions"}],"wp:attachment":[{"href":"https:\/\/concisa.net.ve\/2017\/wp-json\/wp\/v2\/media?parent=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}